{"id":12973,"date":"2020-09-09T19:08:21","date_gmt":"2020-09-10T02:08:21","guid":{"rendered":"https:\/\/www.novogene.com\/us-en\/?page_id=12973"},"modified":"2020-09-15T23:08:41","modified_gmt":"2020-09-16T06:08:41","slug":"clinical-whole-exome-sequencing-service","status":"publish","type":"page","link":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/","title":{"rendered":"Clinical Whole Exome Sequencing Service"},"content":{"rendered":"<div id=\"landing-page10\" style=\"color:#000;\">\n<div style=\"margin-bottom: 20px;padding: 10px;background: #F7F8F8;\"><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 20px;color:#00498A;text-align: center;display: block;padding: 15px;\">High-Quality<span style=\"width: 10px;display: inline-block;\"><\/span>Affordable<span style=\"width: 10px;display: inline-block;\"><\/span>Fast Results<\/strong><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 17px;color: #00498A;text-align: center;display: block;padding-bottom: 15px;\">Contact us today for our current promotional prices, plus additional discounts available for more than 24 samples!<\/strong><\/div>\n<p style=\"font-size: 14px;\">Novogene offers CLIA-validated Whole Exome Sequencing (WES) for investigation or diagnoses of genetic variations underlying cancers, Mendelian diseases, and complex human disorders. <\/p>\n<p style=\"font-size: 14px;\">Whole Exome Sequencing is gaining popularity as a viable and cost-effective alternative to Whole Genome Sequencing: WES targets all protein-coding regions (~1% of the whole genome) responsible for 85% of all disease-causing mutations.<\/p>\n<p><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 17px;color: #00498A;\">Service Features<\/strong><\/p>\n<ul style=\"font-size: 14px;line-height: 30px;\">\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Starting Materials: <\/strong>gDNA, Whole Blood, Saliva, Buccal Swab, and FFPE samples<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Applications: <\/strong>Germline Variants and Somatic Variants<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Sequencing Platform: <\/strong>Illumina NovaSeq 6000 platform<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Sequencing Coverage: <\/strong>50X or 100X<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Turnaround Time: <\/strong>2 Weeks (10 Working Days)<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Quality Assurance: <\/strong>Performed by Licensed Personnel in CLIA-certified Laboratory<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Deliverables: <\/strong>FASTQ, BAM, VCF Files, and Medical Report (optional)<\/li>\n<li><strong style=\"font-family: 'Montserrat-bold', Arial;\">Data Transfer: <\/strong>AWS and Free Data Uploading Services<\/li>\n<\/ul>\n<p><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 17px;color: #00498A;\">Clinical WES Workflow<\/strong><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/09\/20200914151647.jpg\" alt=\"\" \/><\/p>\n<p><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 17px;color: #00498A;\">Performance Metrics<\/strong><\/p>\n<table class=\"table text-center mt-3 four-td mb-0\" style=\"width: 70%;\">\n<tbody>\n<tr>\n<td style=\"text-align: left;background-color: #fff !important;color: #032e53 !important;font-family: 'Montserrat-Regular', Arial !important;border-right: 1px solid #477fb8 !important;width: 60%;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;border-top: 1px solid #fff !important;\">Validated Mean Sequencing Coverage<\/td>\n<td colspan=\"2\" style=\"background-color: #fff !important;color: #032e53 !important;font-family: 'Montserrat-Regular', Arial !important;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;border-top: 1px solid #fff !important;text-align: right;\">103x<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Average Raw Data<\/td>\n<td colspan=\"2\" style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">13.78 G<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Base Pairs Covered at \u226520x<\/td>\n<td colspan=\"2\" style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 94%<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Coverage Uniformity<\/td>\n<td colspan=\"2\" style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 90%<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Mapping Rate<\/td>\n<td colspan=\"2\" style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 97%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Repeatability<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">SNVs<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 98%<\/td>\n<\/tr>\n<tr>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Indels<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 88%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Sensitivity<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">SNVs<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 98%<\/td>\n<\/tr>\n<tr>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Indels<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 90%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\" style=\"text-align: left;border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Specificity<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">SNVs<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 99%<\/td>\n<\/tr>\n<tr>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;\">Indels<\/td>\n<td style=\"border-right: 1px solid #fff !important;border-left: 1px solid #fff !important;text-align: right;\">\u2265 98%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"background: #72AF43;margin: 40px auto;display: table;padding: 10px 30px;border-radius: 15px;\"><a onclick=\"onclicks()\" style=\"font-family: 'Montserrat-bold', Arial;color: #fff;font-weight:bold;font-size: 15px;\" href=\"#\" rel=\"noopener noreferrer\">Download Brochure to Learn More<\/a><\/span><\/p>\n<p><strong style=\"font-family: 'Montserrat-bold', Arial;font-size: 17px;color: #00498A;text-align: center;display: block;\">Contact Us \/ Request Quote<\/strong><br \/>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f12977-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/us-en\/wp-json\/wp\/v2\/pages\/12973#wpcf7-f12977-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"12977\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12977-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:12977,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/>\n<\/div>\n<p><input type=\"hidden\" name=\"_customtoken\" value=\"90c2c34b90dca2c4a9fc78fe135bb1f9\" \/>\n<div class=\"div5\">\n<style>#textarea{border: 1px solid #809EBC;}<\/style>\n<p><input type=\"hidden\" name=\"elqCustomerGUID\" value=\"\"><input type=\"hidden\" name=\"elqCookieWrite\" value=\"0\"><input type=\"hidden\" name=\"elqFormName\" value=\"UnknownFormId-12efb115-81b7-4a9e-a0ff-1250b37bcc7f\"><input type=\"hidden\" name=\"elqSiteID\" value=\"209322265\"><input type=\"hidden\" name=\"elq_form_action\" value=\"https:\/\/om.novogene.com\/e\/f2\"\/>\n<div style=\"clear:both;height: 0px;\"><\/div>\n<div class=\"div4\"><label class=\"label3\">First Name <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap First_Name\"><input type=\"text\" name=\"First_Name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"input3\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div>\n<div class=\"div3\"><label class=\"label3\">Last Name <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Last_Name\"><input type=\"text\" name=\"Last_Name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"input1\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div style=\"clear:both;height: 0px;\"><\/div>\n<div class=\"div4\"><label class=\"label3\">Email <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Email\"><input type=\"email\" name=\"Email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" id=\"input3\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div class=\"div3\"><label class=\"label2\">Phone<span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Phone\"><input type=\"text\" name=\"Phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"input1\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/div>\n<div style=\"clear: both;\"><label class=\"label5\">Institution\/Organization <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Institution_Organization\"><input type=\"text\" name=\"Institution_Organization\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"input5\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/div>\n<div style=\"clear:both;height: 0px;\"><\/div>\n<div class=\"div4\"><label class=\"label3\">Country\/Region <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Country\"><select name=\"Country\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required selectpicker\" id=\"input3\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">Select Country\/Region<\/option><option value=\"United States\">United States<\/option><option value=\"Canada\">Canada<\/option><option value=\"Anguilla\">Anguilla<\/option><option value=\"Antigua and Barbuda\">Antigua and Barbuda<\/option><option value=\"Argentina\">Argentina<\/option><option value=\"Aruba\">Aruba<\/option><option value=\"Barbados\">Barbados<\/option><option value=\"Belize\">Belize<\/option><option value=\"Bermuda\">Bermuda<\/option><option value=\"Bolivia\">Bolivia<\/option><option value=\"Bonaire\">Bonaire<\/option><option value=\"Brazil\">Brazil<\/option><option value=\"British Virgin Islands\">British Virgin Islands<\/option><option value=\"Cayman Islands\">Cayman Islands<\/option><option value=\"Chile\">Chile<\/option><option value=\"Colombia\">Colombia<\/option><option value=\"Costa Rica\">Costa Rica<\/option><option value=\"Cuba\">Cuba<\/option><option value=\"Curacao\">Curacao<\/option><option value=\"Dominica\">Dominica<\/option><option value=\"Dominican Republic\">Dominican Republic<\/option><option value=\"Ecuador\">Ecuador<\/option><option value=\"El Salvador\">El Salvador<\/option><option value=\"Falkland Islands (Malvinas)\">Falkland Islands (Malvinas)<\/option><option value=\"French Guiana\">French Guiana<\/option><option value=\"Greenland\">Greenland<\/option><option value=\"Grenada\">Grenada<\/option><option value=\"Guadeloupe\">Guadeloupe<\/option><option value=\"Guatemala\">Guatemala<\/option><option value=\"Guyana\">Guyana<\/option><option value=\"Haiti\">Haiti<\/option><option value=\"Honduras\">Honduras<\/option><option value=\"Jamaica\">Jamaica<\/option><option value=\"Martinique\">Martinique<\/option><option value=\"Mexico\">Mexico<\/option><option value=\"Montserrat\">Montserrat<\/option><option value=\"Netherlands Antilles\">Netherlands Antilles<\/option><option value=\"Nicaragua\">Nicaragua<\/option><option value=\"Panama\">Panama<\/option><option value=\"Paraguay\">Paraguay<\/option><option value=\"Peru\">Peru<\/option><option value=\"Puerto Rico\">Puerto Rico<\/option><option value=\"Saint Barthelemy\">Saint Barthelemy<\/option><option value=\"Saint Kitts and Nevis\">Saint Kitts and Nevis<\/option><option value=\"Saint Lucia\">Saint Lucia<\/option><option value=\"Saint Martin\">Saint Martin<\/option><option value=\"Saint Pierre and Miquelon\">Saint Pierre and Miquelon<\/option><option value=\"Saint Vincent and the Grenadines\">Saint Vincent and the Grenadines<\/option><option value=\"Sint Maarten (Netherlands)\">Sint Maarten (Netherlands)<\/option><option value=\"Suriname\">Suriname<\/option><option value=\"The Bahamas\">The Bahamas<\/option><option value=\"Trinidad and Tobago\">Trinidad and Tobago<\/option><option value=\"Turks and Caicos Islands\">Turks and Caicos Islands<\/option><option value=\"United States Minor Outlying Islands\">United States Minor Outlying Islands<\/option><option value=\"United States Virgin Islands\">United States Virgin Islands<\/option><option value=\"Uruguay\">Uruguay<\/option><option value=\"Venezuela\">Venezuela<\/option><\/select><\/span><\/div>\n<div class=\"div3\"><label class=\"label3\">States <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap States\"><select name=\"States\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required selectpicker\" id=\"input1\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">Select States<\/option><option value=\"Non-US\">Non-US<\/option><option value=\"Alabama\">Alabama<\/option><option value=\"Alaska\">Alaska<\/option><option value=\"Arizona\">Arizona<\/option><option value=\"Arkansas\">Arkansas<\/option><option value=\"California\">California<\/option><option value=\"Colorado\">Colorado<\/option><option value=\"Connecticut\">Connecticut<\/option><option value=\"Delaware\">Delaware<\/option><option value=\"Florida\">Florida<\/option><option value=\"Georgia\">Georgia<\/option><option value=\"Hawaii\">Hawaii<\/option><option value=\"Idaho\">Idaho<\/option><option value=\"Illinois\">Illinois<\/option><option value=\"Indiana\">Indiana<\/option><option value=\"Iowa\">Iowa<\/option><option value=\"Kansas\">Kansas<\/option><option value=\"Kentucky\">Kentucky<\/option><option value=\"Louisiana\">Louisiana<\/option><option value=\"Maine\">Maine<\/option><option value=\"Maryland\">Maryland<\/option><option value=\"Massachusetts\">Massachusetts<\/option><option value=\"Michigan\">Michigan<\/option><option value=\"Minnesota\">Minnesota<\/option><option value=\"Mississippi\">Mississippi<\/option><option value=\"Missouri\">Missouri<\/option><option value=\"Montana\">Montana<\/option><option value=\"Nebraska\">Nebraska<\/option><option value=\"Nevada\">Nevada<\/option><option value=\"New Hampshire\">New Hampshire<\/option><option value=\"New Jersey\">New Jersey<\/option><option value=\"New Mexico\">New Mexico<\/option><option value=\"New York\">New York<\/option><option value=\"North Carolina\">North Carolina<\/option><option value=\"North Dakota\">North Dakota<\/option><option value=\"Ohio\">Ohio<\/option><option value=\"Oklahoma\">Oklahoma<\/option><option value=\"Oregon\">Oregon<\/option><option value=\"Pennsylvania\">Pennsylvania<\/option><option value=\"Rhode Island\">Rhode Island<\/option><option value=\"South Carolina\">South Carolina<\/option><option value=\"South Dakota\">South Dakota<\/option><option value=\"Tennessee\">Tennessee<\/option><option value=\"Texas\">Texas<\/option><option value=\"Utah\">Utah<\/option><option value=\"Vermont\">Vermont<\/option><option value=\"Virginia\">Virginia<\/option><option value=\"Washington\">Washington<\/option><option value=\"Washington DC\">Washington DC<\/option><option value=\"West Virginia\">West Virginia<\/option><option value=\"Wisconsin\">Wisconsin<\/option><option value=\"Wyoming\">Wyoming<\/option><\/select><\/span><\/div>\n<div style=\"clear: both;\"><label class=\"label5\">Comments\/Questions? <span class=\"span1\">*<\/span><\/label><span class=\"wpcf7-form-control-wrap Comments_Questions\"><textarea name=\"Comments_Questions\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"textarea\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span><\/div>\n<div class=\"col-xs-12 col-sm-12 col-md-12 col-lg-12\"><span class=\"wpcf7-form-control-wrap kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"> \n    <span class=\"captcha-image\" >\n        <span class=\"cf7ic_instructions\">Please prove you are human by selecting the <span> Heart<\/span>.<\/span><label><input type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M259 18l-65 132-146 22c-26 3-37 36-18 54l106 103-25 146c-5 26 23 46 46 33l131-68 131 68c23 13 51-7 46-33l-25-146 106-103c19-18 8-51-18-54l-146-22-65-132a32 32 0 00-58 0z\"\/><\/svg><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg width=\"50\" height=\"50\" aria-hidden=\"true\" role=\"img\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M500 168h-55l-8-21a127 127 0 00-120-83H195a127 127 0 00-120 83l-8 21H12c-8 0-14 8-11 16l8 24a12 12 0 0011 8h29a64 64 0 00-33 56v48c0 16 6 31 16 42v62c0 13 11 24 24 24h48c13 0 24-11 24-24v-40h256v40c0 13 11 24 24 24h48c13 0 24-11 24-24v-62c10-11 16-26 16-42v-48c0-24-13-45-33-56h29a12 12 0 0011-8l8-24c3-8-3-16-11-16zm-365 2c9-25 33-42 60-42h122c27 0 51 17 60 42l15 38H120l15-38zM88 328a32 32 0 010-64c18 0 48 30 48 48s-30 16-48 16zm336 0c-18 0-48 2-48-16s30-48 48-48 32 14 32 32-14 32-32 32z\"\/><\/svg><\/label>\n    <\/span>\n    <span style=\"display:none\">\n        <input type=\"text\" name=\"kc_honeypot\">\n    <\/span><\/span><\/span><\/div>\n<div style=\"clear:both;height: 0px;\"><\/div>\n<p><span class=\"wpcf7-form-control-wrap acceptance_as_validationon\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance_as_validation:on\" value=\"1\" aria-invalid=\"false\" id=\"acceptance_as_validation\" \/><\/span><\/span><\/span>\n<p class=\"p-1\">I agree that Novogene Corporation may use this information to contact me to assist with my request. I understand that all personal information I have submitted will be kept confidential in accordance with Novogene's <a href=\"https:\/\/www.novogene.com\/us-en\/privacy-policy\/\">privacy policy<\/a>.<\/p>\n<div style=\"clear:both;\"><\/div>\n<p style=\"text-align:center;\"><input type=\"submit\" value=\"submit\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div><\/p>\n<div class=\"div1\"><\/div>\n<p><img decoding=\"async\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/07\/20200716143857.jpg\" alt=\"\" class=\"img2\" \/><\/p>\n<div class=\"div2\">\n<h5 style=\"color:#032e53\">Novogene Corporation Inc.<\/h5>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/07\/20200716150837.jpg\" alt=\"\" width=\"12\" height=\"15\" class=\"alignnone size-full wp-image-10311\" \/><strong style=\"padding-left: 7px\">8801 Folsom Blvd #290, Sacramento, CA 95826<\/strong><\/p>\n<ul class=\"ul1\">\n<li><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/07\/20200716150559.jpg\" alt=\"\" width=\"22\" height=\"16\" class=\"alignnone size-full wp-image-10307\" \/><strong style=\"padding-left: 7px\"><a target=\"_blank\" href=\"tel:916-252-0068-383\" rel=\"noopener noreferrer\">916-252-0068-383<\/a><\/strong><\/li>\n<li class=\"li1\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/07\/20200716151044.jpg\" alt=\"\" width=\"18\" height=\"12\" class=\"alignnone size-full wp-image-10315\" \/><strong style=\"padding-left: 7px\"><a target=\"_blank\" href=\"mailto:inquiry_us@novogene.com\" rel=\"noopener noreferrer\">inquiry_us@novogene.com<\/a><\/strong><\/li>\n<li><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/07\/20200716151140.jpg\" alt=\"\" width=\"19\" height=\"18\" class=\"alignnone size-full wp-image-10317\" \/><strong style=\"padding-left: 7px\"><a target=\"_blank\" href=\"https:\/\/www.novogene.com\/us-en\/\" rel=\"noopener noreferrer\">novogene.com\/us-en<\/a><\/strong><\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<p>Copyright\u00a92011-2020 Novogene Corporation<br \/>\nAll Rights Reserved. Information and specifications are subject to change at any time without notice.\n<\/p><\/div>\n<div style=\"clear:both\"><\/div>\n<p><script>function onclicks(){var url = 'https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/09\/WES-Brochure.pdf';window.open(url);}<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>High-QualityAffordableFast ResultsContact us today for our current promotional prices, plus additional discounts available for more than 24 samples! Novogene offers CLIA-validated Whole Exome Sequencing (WES) for investigation or diagnoses of genetic variations underlying cancers, Mendelian diseases, and complex human disorders. Whole Exome Sequencing is gaining popularity as a viable and cost-effective alternative to Whole Genome<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":12519,"menu_order":48,"comment_status":"closed","ping_status":"closed","template":"templates\/blank-template.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v20.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Clinical Whole Exome Sequencing Service - Novogene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clinical Whole Exome Sequencing Service\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Novogene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NovogeneAmerica\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-16T06:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/09\/20200914151647.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Novogene_Global\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/\",\"url\":\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/\",\"name\":\"Clinical Whole Exome Sequencing Service - Novogene\",\"isPartOf\":{\"@id\":\"https:\/\/www.novogene.com\/us-en\/#website\"},\"datePublished\":\"2020-09-10T02:08:21+00:00\",\"dateModified\":\"2020-09-16T06:08:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.novogene.com\/us-en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"landing page\",\"item\":\"https:\/\/www.novogene.com\/us-en\/landing-page\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clinical Whole Exome Sequencing Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.novogene.com\/us-en\/#website\",\"url\":\"https:\/\/www.novogene.com\/us-en\/\",\"name\":\"Novogene\",\"description\":\"USA Based Lab Guaranteed Data Security\",\"publisher\":{\"@id\":\"https:\/\/www.novogene.com\/us-en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.novogene.com\/us-en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.novogene.com\/us-en\/#organization\",\"name\":\"Novogene\",\"url\":\"https:\/\/www.novogene.com\/us-en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.novogene.com\/us-en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/05\/20200506113246.png\",\"contentUrl\":\"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/05\/20200506113246.png\",\"width\":941,\"height\":269,\"caption\":\"Novogene\"},\"image\":{\"@id\":\"https:\/\/www.novogene.com\/us-en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/NovogeneAmerica\/\",\"https:\/\/twitter.com\/Novogene_Global\",\"https:\/\/www.linkedin.com\/company\/novogene\/\",\"https:\/\/www.youtube.com\/c\/NovogeneGlobal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Clinical Whole Exome Sequencing Service - Novogene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/","og_locale":"en_US","og_type":"article","og_title":"Clinical Whole Exome Sequencing Service","og_url":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/","og_site_name":"Novogene","article_publisher":"https:\/\/www.facebook.com\/NovogeneAmerica\/","article_modified_time":"2020-09-16T06:08:41+00:00","og_image":[{"url":"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/09\/20200914151647.jpg"}],"twitter_card":"summary_large_image","twitter_site":"@Novogene_Global","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/","url":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/","name":"Clinical Whole Exome Sequencing Service - Novogene","isPartOf":{"@id":"https:\/\/www.novogene.com\/us-en\/#website"},"datePublished":"2020-09-10T02:08:21+00:00","dateModified":"2020-09-16T06:08:41+00:00","breadcrumb":{"@id":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.novogene.com\/us-en\/landing-page\/clinical-whole-exome-sequencing-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.novogene.com\/us-en\/"},{"@type":"ListItem","position":2,"name":"landing page","item":"https:\/\/www.novogene.com\/us-en\/landing-page\/"},{"@type":"ListItem","position":3,"name":"Clinical Whole Exome Sequencing Service"}]},{"@type":"WebSite","@id":"https:\/\/www.novogene.com\/us-en\/#website","url":"https:\/\/www.novogene.com\/us-en\/","name":"Novogene","description":"USA Based Lab Guaranteed Data Security","publisher":{"@id":"https:\/\/www.novogene.com\/us-en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.novogene.com\/us-en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.novogene.com\/us-en\/#organization","name":"Novogene","url":"https:\/\/www.novogene.com\/us-en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.novogene.com\/us-en\/#\/schema\/logo\/image\/","url":"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/05\/20200506113246.png","contentUrl":"https:\/\/www.novogene.com\/us-en\/wp-content\/uploads\/sites\/4\/2020\/05\/20200506113246.png","width":941,"height":269,"caption":"Novogene"},"image":{"@id":"https:\/\/www.novogene.com\/us-en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NovogeneAmerica\/","https:\/\/twitter.com\/Novogene_Global","https:\/\/www.linkedin.com\/company\/novogene\/","https:\/\/www.youtube.com\/c\/NovogeneGlobal"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/pages\/12973"}],"collection":[{"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/comments?post=12973"}],"version-history":[{"count":88,"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/pages\/12973\/revisions"}],"predecessor-version":[{"id":30511,"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/pages\/12973\/revisions\/30511"}],"up":[{"embeddable":true,"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/pages\/12519"}],"wp:attachment":[{"href":"https:\/\/www.novogene.com\/us-en\/wp-json\/wp\/v2\/media?parent=12973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}